{"id":3811,"date":"2015-06-05T10:00:33","date_gmt":"2015-06-05T08:00:33","guid":{"rendered":"http:\/\/www.sporttennis.it\/sef-italia\/?p=3811"},"modified":"2016-10-20T09:11:20","modified_gmt":"2016-10-20T07:11:20","slug":"la-monta-a-pelo","status":"publish","type":"post","link":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/","title":{"rendered":"La Monta A Pelo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3812 alignleft\" src=\"http:\/\/www.sef.italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg\" alt=\"monta_pelo-ecbb7545\" width=\"250\" height=\"115\" srcset=\"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg 250w, https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545-230x106.jpg 230w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Il cavaliere nella monta a pelo non gode dell\u2019appoggio fornito dalle staffe e dalla sella, ma controller\u00e0 il cavallo attraverso il suo peso e il suo equilibrio. Si dice monta a pelo poich\u00e9 si ha il contatto diretto con il dorso dell\u2019animale. Con questo tipo di equitazione si ricerca un contatto emotivo, fisico e psicologico tra uomo e cavallo.<\/p>\n<p>\u00c8 necessario avere una conoscenza dell\u2019equitazione e dare correttamente i segnali con le gambe. Senza la sella i piedi non hanno l\u2019appoggio pertanto \u00e8 fondamentale saper cadere molto bene, avere un equilibrio molto stabile e avere un cavallo molto tranquillo e obbediente. L\u2019assetto con la sella \u00e8 diverso da quello senza. I talloni, comunque, vanno tenuti bassi come se ci fossero delle staffe da premere perch\u00e9 questa posizione produce automaticamente quella corretta delle gambe e del tronco. Vengono utilizzati muscoli diversi a seconda che si cavalchi con la sella o senza.<\/p>\n<p>Il corpo del cavaliere deve trovare un equilibrio in armonia con quello del cavallo in modo da accompagnare naturalmente i movimenti dello stesso. Questo adattamento richiede una graduale costruzione di risposte neuromuscolari a stimoli che riceverebbero risposte diverse se solo si avessero i piedi appoggiati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cavaliere nella monta a pelo non gode dell\u2019appoggio fornito dalle staffe e dalla sella, ma controller\u00e0 il cavallo attraverso il suo [&hellip;]<\/p>\n","protected":false},"author":83,"featured_media":3812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>La Monta A Pelo - SEF Italia<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"La Monta A Pelo - SEF Italia\" \/>\r\n<meta property=\"og:description\" content=\"Il cavaliere nella monta a pelo non gode dell\u2019appoggio fornito dalle staffe e dalla sella, ma controller\u00e0 il cavallo attraverso il suo [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/\" \/>\r\n<meta property=\"og:site_name\" content=\"SEF Italia\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scuolaequestrediformazione\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2015-06-05T08:00:33+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2016-10-20T07:11:20+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"250\" \/>\r\n\t<meta property=\"og:image:height\" content=\"115\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Maria Teresa Bevilacqua\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@sef_italia\" \/>\r\n<meta name=\"twitter:site\" content=\"@sef_italia\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Teresa Bevilacqua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/\"},\"author\":{\"name\":\"Maria Teresa Bevilacqua\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#\\\/schema\\\/person\\\/98bbf141ebc34928c1b6b3262203ee9e\"},\"headline\":\"La Monta A Pelo\",\"datePublished\":\"2015-06-05T08:00:33+00:00\",\"dateModified\":\"2016-10-20T07:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/monta_pelo-ecbb7545.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/\",\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/\",\"name\":\"La Monta A Pelo - SEF Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/monta_pelo-ecbb7545.jpg\",\"datePublished\":\"2015-06-05T08:00:33+00:00\",\"dateModified\":\"2016-10-20T07:11:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/monta_pelo-ecbb7545.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/monta_pelo-ecbb7545.jpg\",\"width\":250,\"height\":115},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/2015\\\/06\\\/05\\\/la-monta-a-pelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sef-italia.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Monta A Pelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/\",\"name\":\"SEF Italia\",\"description\":\"Il nuovo sito SEF Italia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sef-italia.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#organization\",\"name\":\"SEF Italia\",\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logoSEF_QUADRATO-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sef-italia.it\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logoSEF_QUADRATO-.jpg\",\"width\":600,\"height\":600,\"caption\":\"SEF Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scuolaequestrediformazione\\\/\",\"https:\\\/\\\/x.com\\\/sef_italia\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcEMamL3elnrqfrtIT8sh7g?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sef-italia.it\\\/#\\\/schema\\\/person\\\/98bbf141ebc34928c1b6b3262203ee9e\",\"name\":\"Maria Teresa Bevilacqua\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g\",\"caption\":\"Maria Teresa Bevilacqua\"},\"url\":\"https:\\\/\\\/www.sef-italia.it\\\/index.php\\\/author\\\/mariateresa\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Monta A Pelo - SEF Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/","og_locale":"it_IT","og_type":"article","og_title":"La Monta A Pelo - SEF Italia","og_description":"Il cavaliere nella monta a pelo non gode dell\u2019appoggio fornito dalle staffe e dalla sella, ma controller\u00e0 il cavallo attraverso il suo [&hellip;]","og_url":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/","og_site_name":"SEF Italia","article_publisher":"https:\/\/www.facebook.com\/scuolaequestrediformazione\/","article_published_time":"2015-06-05T08:00:33+00:00","article_modified_time":"2016-10-20T07:11:20+00:00","og_image":[{"width":250,"height":115,"url":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg","type":"image\/jpeg"}],"author":"Maria Teresa Bevilacqua","twitter_card":"summary_large_image","twitter_creator":"@sef_italia","twitter_site":"@sef_italia","twitter_misc":{"Scritto da":"Maria Teresa Bevilacqua","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#article","isPartOf":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/"},"author":{"name":"Maria Teresa Bevilacqua","@id":"https:\/\/www.sef-italia.it\/#\/schema\/person\/98bbf141ebc34928c1b6b3262203ee9e"},"headline":"La Monta A Pelo","datePublished":"2015-06-05T08:00:33+00:00","dateModified":"2016-10-20T07:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/www.sef-italia.it\/#organization"},"image":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg","articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/","url":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/","name":"La Monta A Pelo - SEF Italia","isPartOf":{"@id":"https:\/\/www.sef-italia.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#primaryimage"},"image":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg","datePublished":"2015-06-05T08:00:33+00:00","dateModified":"2016-10-20T07:11:20+00:00","breadcrumb":{"@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#primaryimage","url":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg","contentUrl":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2016\/10\/monta_pelo-ecbb7545.jpg","width":250,"height":115},{"@type":"BreadcrumbList","@id":"https:\/\/www.sef-italia.it\/index.php\/2015\/06\/05\/la-monta-a-pelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sef-italia.it\/"},{"@type":"ListItem","position":2,"name":"La Monta A Pelo"}]},{"@type":"WebSite","@id":"https:\/\/www.sef-italia.it\/#website","url":"https:\/\/www.sef-italia.it\/","name":"SEF Italia","description":"Il nuovo sito SEF Italia","publisher":{"@id":"https:\/\/www.sef-italia.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sef-italia.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.sef-italia.it\/#organization","name":"SEF Italia","url":"https:\/\/www.sef-italia.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sef-italia.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2018\/01\/logoSEF_QUADRATO-.jpg","contentUrl":"https:\/\/www.sef-italia.it\/wp-content\/uploads\/2018\/01\/logoSEF_QUADRATO-.jpg","width":600,"height":600,"caption":"SEF Italia"},"image":{"@id":"https:\/\/www.sef-italia.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scuolaequestrediformazione\/","https:\/\/x.com\/sef_italia","https:\/\/www.youtube.com\/channel\/UCcEMamL3elnrqfrtIT8sh7g?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/www.sef-italia.it\/#\/schema\/person\/98bbf141ebc34928c1b6b3262203ee9e","name":"Maria Teresa Bevilacqua","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80545e0235d38a23ac5a48fadb4c4be36f3db17c532d5dac1d9e840daf46f0d5?s=96&d=mm&r=g","caption":"Maria Teresa Bevilacqua"},"url":"https:\/\/www.sef-italia.it\/index.php\/author\/mariateresa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/posts\/3811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/comments?post=3811"}],"version-history":[{"count":3,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/posts\/3811\/revisions"}],"predecessor-version":[{"id":5903,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/posts\/3811\/revisions\/5903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/media\/3812"}],"wp:attachment":[{"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/media?parent=3811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/categories?post=3811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sef-italia.it\/index.php\/wp-json\/wp\/v2\/tags?post=3811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}